{"id":35050,"date":"2025-04-02T18:29:31","date_gmt":"2025-04-02T17:29:31","guid":{"rendered":"https:\/\/www.dexeuscampus.com\/?page_id=35050"},"modified":"2026-03-09T15:55:16","modified_gmt":"2026-03-09T14:55:16","slug":"masters-postgraduates","status":"publish","type":"page","link":"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/","title":{"rendered":"Masters and Postgraduates Degrees"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"35050\" class=\"elementor elementor-35050 elementor-33868\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f14825 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f14825\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f3fbed5\" data-id=\"f3fbed5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-504cd51 elementor-widget elementor-widget-global elementor-global-15972 elementor-widget-shortcode\" data-id=\"504cd51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/www.dexeuscampus.com\/en\/\" rel=\"nofollow\">Home<\/a>&nbsp;&nbsp;&#187;&nbsp;&nbsp;Masters and Postgraduates Degrees\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca3c65c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca3c65c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1847e7\" data-id=\"f1847e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-90b8575 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90b8575\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bfb913b\" data-id=\"bfb913b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afdebb0 elementor-cta--skin-cover elementor-cta--valign-bottom elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"afdebb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"#master_biologia\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2025\/01\/Dexeus-Campus-Master-1024x683-2.jpg);\" role=\"img\" aria-label=\"Master en Biolog\u00eda de la Reproducci\u00f3n y TRA de Dexeus &amp; UAB\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tMaster in Biology\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa42949 elementor-widget elementor-widget-heading\" data-id=\"fa42949\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Master's Degree in Reproductive Biology and Assisted Human Reproduction Techniques<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-532bbc8\" data-id=\"532bbc8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9f6004 elementor-cta--skin-cover elementor-cta--valign-bottom elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"d9f6004\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"#master_ecografia\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2023\/02\/destacados-master-dgi.jpg);\" role=\"img\" aria-label=\"M\u00e1ster en Ecograf\u00eda Ginecol\u00f3gica, Obst\u00e9trica y Mamaria\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tMaster in Ultrasound\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5e37d9 elementor-widget elementor-widget-heading\" data-id=\"a5e37d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Master's Degree in Gynecological, Obstetric and Breast Ultrasound<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-072cf91\" data-id=\"072cf91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b19ff6 elementor-cta--skin-cover elementor-cta--valign-bottom elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"6b19ff6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"#diploma_biologia\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2021\/09\/Diploma-Postgrado.jpg);\" role=\"img\" aria-label=\"Diploma de Postgrado\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tPostgraduate in Biology\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3115e7 elementor-widget elementor-widget-heading\" data-id=\"e3115e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Expert Diploma in Reproductive Biology and Assisted Human Reproduction Techniques<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-934d3f8 elementor-widget elementor-widget-menu-anchor\" data-id=\"934d3f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"master_biologia\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b67ce58 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b67ce58\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-08ed74a\" data-id=\"08ed74a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e8aebc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5e8aebc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f2ed2a elementor-reverse-tablet elementor-reverse-mobile elementor-reverse-mobile_extra elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f2ed2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a60c13a\" data-id=\"a60c13a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9ff9a0 elementor-widget elementor-widget-spacer\" data-id=\"f9ff9a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0ca0af elementor-widget elementor-widget-menu-anchor\" data-id=\"b0ca0af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"master_ecografia\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-8c6821a\" data-id=\"8c6821a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c0e769 elementor-widget elementor-widget-heading\" data-id=\"3c0e769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Master's Degree in Reproductive Biology and Assisted Human Reproduction Techniques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5483b3c elementor-widget elementor-widget-text-editor\" data-id=\"5483b3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>This Master\u2019s jointly organised by Dexeus Mujer and the Department of Cell Biology, Physiology and Immunology of the UAB has a long tradition, with recognised prestige among professionals in Clinical Embryology, both in Spain and abroad, and a high level of employment opportunities.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2bf4db elementor-widget elementor-widget-text-editor\" data-id=\"b2bf4db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"margin: 5px 0px; padding: 5px 0px 5px 8px; background-color: #ffa518; color: #ffffff; font-weight: 600;\">Registration open for 2026-2027. Very limited places. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ac90e2 elementor-widget elementor-widget-button\" data-id=\"7ac90e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/master-reproductive-biology\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Information and access to the Master<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0773105 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0773105\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ecbfd11\" data-id=\"ecbfd11\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16f0ddf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"16f0ddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af6b292 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af6b292\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-68eeb42\" data-id=\"68eeb42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-440a03c elementor-widget elementor-widget-heading\" data-id=\"440a03c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Master's Degree in Gynecological, Obstetric and Breast Ultrasound<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ac00bd elementor-widget elementor-widget-text-editor\" data-id=\"6ac00bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Advanced theoretical and practical training in gynaecological and obstetric ultrasound, taught by internationally renowned experts. Accredited programme, with access to state-of-the-art technology and intensive clinical practice in a high-level hospital environment. <\/p><p><strong style=\"color: #537b8d;\">This master\u2019s degree is aimed at graduates in Nursing, Radiodiagnosis Specialist Technician (RST) and Superior Diagnostic Imaging Technician (SDIT).<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cd27f5 elementor-widget elementor-widget-text-editor\" data-id=\"2cd27f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"margin: 5px 0px; padding: 5px 0px 5px 8px; background-color: #ffa518; color: #ffffff; font-weight: 600;\">Registration open for 2025-2026. Very limited places. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d8bf0b elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"1d8bf0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/master-gynaecological-ultrasound\/\" title=\"M\u00e1s informaci\u00f3n\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Information and access to the Master<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2298375\" data-id=\"2298375\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59e743a elementor-widget elementor-widget-spacer\" data-id=\"59e743a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2af6ee elementor-widget elementor-widget-menu-anchor\" data-id=\"e2af6ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"diploma_biologia\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40939af elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40939af\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f838f1f\" data-id=\"f838f1f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30da2b1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"30da2b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af85afb elementor-reverse-mobile elementor-reverse-tablet elementor-reverse-mobile_extra elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af85afb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-16c437f\" data-id=\"16c437f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a975702 elementor-widget elementor-widget-spacer\" data-id=\"a975702\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-722a3f9\" data-id=\"722a3f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59e21a4 elementor-widget elementor-widget-heading\" data-id=\"59e21a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Postgraduate degree in Reproductive Biology and Assisted Human Reproduction Techniques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-067eadc elementor-widget elementor-widget-text-editor\" data-id=\"067eadc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>This Expert Diploma aims to provide professionals, people involved in Assisted Reproduction Techniques and students interested in learning more about new technologies related to assisted human reproduction.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5175941 elementor-widget elementor-widget-text-editor\" data-id=\"5175941\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"margin: 5px 0px; padding: 5px 0px 5px 8px; background-color: #ffa518; color: #ffffff; font-weight: 600;\">Registration open for 2026-2027. Very limited places. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63d711e elementor-widget elementor-widget-button\" data-id=\"63d711e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/postgraduate-reproductive-biology\/\" title=\"Informaci\u00f3n y acceso al Diploma\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Information and access to the Postgraduate<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-656ec3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"656ec3f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5a781d\" data-id=\"f5a781d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45277a4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"45277a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9a84a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9a84a1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5eee162\" data-id=\"5eee162\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b5e1fb elementor-widget elementor-widget-video\" data-id=\"2b5e1fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.dexeuscampus.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Captura-de-Pantalla-2021-06-10-a-les-17.36.58.png&quot;,&quot;id&quot;:3273,&quot;size&quot;:&quot;&quot;},&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2021\/06\/BIOLOGO-LLUC_ESP.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\" poster=\"https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2021\/06\/Captura-de-Pantalla-2021-06-10-a-les-17.36.58.png\"><\/video>\n\t\t\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2021\/06\/Captura-de-Pantalla-2021-06-10-a-les-17.36.58.png);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Play Video\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-b4e2d4f\" data-id=\"b4e2d4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a767c1 elementor-widget elementor-widget-text-editor\" data-id=\"5a767c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00abWhen you start to train, it is essential to have referents of the highest quality, rigour, enthusiasm and excellence. In Dexeus you find these references \u00bb.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-164193f elementor-widget elementor-widget-text-editor\" data-id=\"164193f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lluc Coll Lujan<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3989cae elementor-widget elementor-widget-text-editor\" data-id=\"3989cae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Biologist of the Reproductive Medicine Service<br>Former student of the Master<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Master in Biology Master&#8217;s Degree in Reproductive Biology and Assisted Human Reproduction Techniques Master in Ultrasound Master&#8217;s Degree in Gynecological, Obstetric and Breast Ultrasound Postgraduate in Biology Expert Diploma in Reproductive Biology and Assisted Human Reproduction Techniques Master&#8217;s Degree in Reproductive Biology and Assisted Human Reproduction Techniques This Master\u2019s jointly organised by Dexeus Mujer and [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34895,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-35050","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Masters and Postgraduates Degrees - Dexeus Campus<\/title>\n<meta name=\"description\" content=\"Master in Biology Master&#039;s Degree in Reproductive Biology and Assisted Human Reproduction Techniques Master in Ultrasound Master&#039;s Degree in\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Masters and Postgraduates Degrees - Dexeus Campus\" \/>\n<meta property=\"og:description\" content=\"Master in Biology Master&#039;s Degree in Reproductive Biology and Assisted Human Reproduction Techniques Master in Ultrasound Master&#039;s Degree in\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/\" \/>\n<meta property=\"og:site_name\" content=\"Dexeus Campus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CampusDexeus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T14:55:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2025\/03\/masters-postgrados.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DexeusCampus\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/masters-postgraduates\\\/\",\"url\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/masters-postgraduates\\\/\",\"name\":\"Masters and Postgraduates Degrees - Dexeus Campus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/masters-postgraduates\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/masters-postgraduates\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dexeuscampus.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/masters-postgrados.png\",\"datePublished\":\"2025-04-02T17:29:31+00:00\",\"dateModified\":\"2026-03-09T14:55:16+00:00\",\"description\":\"Master in Biology Master's Degree in Reproductive Biology and Assisted Human Reproduction Techniques Master in Ultrasound Master's Degree in\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/masters-postgraduates\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/masters-postgraduates\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/masters-postgraduates\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dexeuscampus.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/masters-postgrados.png\",\"contentUrl\":\"https:\\\/\\\/www.dexeuscampus.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/masters-postgrados.png\",\"width\":500,\"height\":375,\"caption\":\"M\u00e1sters y Postgrados\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/masters-postgraduates\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Masters and Postgraduates Degrees\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/\",\"name\":\"Dexeus Campus\",\"description\":\"Plataforma online dirigida a los profesionales especializados en obstetricia, ginecolog\u00eda y reproducci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/#organization\",\"name\":\"DEXEUS CAMPUS. FUNDACION DEXEUS MUJER\",\"url\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dexeuscampus.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-Campus-Dexeus.png\",\"contentUrl\":\"https:\\\/\\\/www.dexeuscampus.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-Campus-Dexeus.png\",\"width\":2068,\"height\":1773,\"caption\":\"DEXEUS CAMPUS. FUNDACION DEXEUS MUJER\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dexeuscampus.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CampusDexeus\",\"https:\\\/\\\/x.com\\\/DexeusCampus\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/DexeusCampus\",\"https:\\\/\\\/vimeo.com\\\/dexeuscampus\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dexeusmujer\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Masters and Postgraduates Degrees - Dexeus Campus","description":"Master in Biology Master's Degree in Reproductive Biology and Assisted Human Reproduction Techniques Master in Ultrasound Master's Degree in","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/","og_locale":"en_US","og_type":"article","og_title":"Masters and Postgraduates Degrees - Dexeus Campus","og_description":"Master in Biology Master's Degree in Reproductive Biology and Assisted Human Reproduction Techniques Master in Ultrasound Master's Degree in","og_url":"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/","og_site_name":"Dexeus Campus","article_publisher":"https:\/\/www.facebook.com\/CampusDexeus","article_modified_time":"2026-03-09T14:55:16+00:00","og_image":[{"width":500,"height":375,"url":"https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2025\/03\/masters-postgrados.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@DexeusCampus","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/","url":"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/","name":"Masters and Postgraduates Degrees - Dexeus Campus","isPartOf":{"@id":"https:\/\/www.dexeuscampus.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/#primaryimage"},"image":{"@id":"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2025\/03\/masters-postgrados.png","datePublished":"2025-04-02T17:29:31+00:00","dateModified":"2026-03-09T14:55:16+00:00","description":"Master in Biology Master's Degree in Reproductive Biology and Assisted Human Reproduction Techniques Master in Ultrasound Master's Degree in","breadcrumb":{"@id":"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/#primaryimage","url":"https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2025\/03\/masters-postgrados.png","contentUrl":"https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2025\/03\/masters-postgrados.png","width":500,"height":375,"caption":"M\u00e1sters y Postgrados"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dexeuscampus.com\/en\/masters-postgraduates\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.dexeuscampus.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Masters and Postgraduates Degrees"}]},{"@type":"WebSite","@id":"https:\/\/www.dexeuscampus.com\/en\/#website","url":"https:\/\/www.dexeuscampus.com\/en\/","name":"Dexeus Campus","description":"Plataforma online dirigida a los profesionales especializados en obstetricia, ginecolog\u00eda y reproducci\u00f3n","publisher":{"@id":"https:\/\/www.dexeuscampus.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dexeuscampus.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dexeuscampus.com\/en\/#organization","name":"DEXEUS CAMPUS. FUNDACION DEXEUS MUJER","url":"https:\/\/www.dexeuscampus.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dexeuscampus.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2021\/03\/Logo-Campus-Dexeus.png","contentUrl":"https:\/\/www.dexeuscampus.com\/wp-content\/uploads\/2021\/03\/Logo-Campus-Dexeus.png","width":2068,"height":1773,"caption":"DEXEUS CAMPUS. FUNDACION DEXEUS MUJER"},"image":{"@id":"https:\/\/www.dexeuscampus.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CampusDexeus","https:\/\/x.com\/DexeusCampus","https:\/\/www.youtube.com\/user\/DexeusCampus","https:\/\/vimeo.com\/dexeuscampus","https:\/\/www.linkedin.com\/company\/dexeusmujer"]}]}},"_links":{"self":[{"href":"https:\/\/www.dexeuscampus.com\/en\/wp-json\/wp\/v2\/pages\/35050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dexeuscampus.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dexeuscampus.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dexeuscampus.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dexeuscampus.com\/en\/wp-json\/wp\/v2\/comments?post=35050"}],"version-history":[{"count":11,"href":"https:\/\/www.dexeuscampus.com\/en\/wp-json\/wp\/v2\/pages\/35050\/revisions"}],"predecessor-version":[{"id":37987,"href":"https:\/\/www.dexeuscampus.com\/en\/wp-json\/wp\/v2\/pages\/35050\/revisions\/37987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dexeuscampus.com\/en\/wp-json\/wp\/v2\/media\/34895"}],"wp:attachment":[{"href":"https:\/\/www.dexeuscampus.com\/en\/wp-json\/wp\/v2\/media?parent=35050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}